{"id":64,"count":1,"description":"","link":"https:\/\/bourgogneselect.com\/zh\/category\/cepages-connaissances-du-vin\/","name":"\u8461\u8404\u54c1\u79cd\u548c\u8461\u8404\u9152\u77e5\u8bc6","slug":"cepages-connaissances-du-vin","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/bourgogneselect.com\/zh\/wp-json\/wp\/v2\/categories\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bourgogneselect.com\/zh\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/bourgogneselect.com\/zh\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/bourgogneselect.com\/zh\/wp-json\/wp\/v2\/posts?categories=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}